{"id":2001,"date":"2022-09-05T14:34:12","date_gmt":"2022-09-05T14:34:12","guid":{"rendered":"https:\/\/www.kidemy.hk\/blog\/?p=2001"},"modified":"2023-07-16T22:55:46","modified_gmt":"2023-07-16T14:55:46","slug":"norwegian-international-school","status":"publish","type":"page","link":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/","title":{"rendered":"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? &#8211; 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a"},"content":{"rendered":"\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-table is-style-regular\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e4%b8%ad%e8%a5%bf%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u4e2d\u897f\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e7%81%a3%e4%bb%94%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u7063\u4ed4\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e6%9d%b1%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u6771\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e5%8d%97%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u5357\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e6%b2%b9%e5%b0%96%e6%97%ba%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u6cb9\u5c16\u65fa\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e6%b7%b1%e6%b0%b4%e5%9f%97%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u6df1\u6c34\u57d7\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e4%b9%9d%e9%be%8d%e5%a1%98%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u4e5d\u9f8d\u57ce\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e9%bb%83%e5%a4%a7%e4%bb%99%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u9ec3\u5927\u4ed9\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e8%a7%80%e5%a1%98%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u89c0\u5858\u5340<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e8%91%b5%e9%9d%92%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u8475\u9752\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e8%8d%83%e7%81%a3%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u8343\u7063\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e5%b1%af%e9%96%80%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u5c6f\u9580\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e5%85%83%e6%9c%97%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u5143\u6717\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e9%9b%a2%e5%b3%b6%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u96e2\u5cf6\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e5%8c%97%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u5317\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e5%a4%a7%e5%9f%94%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u5927\u57d4\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e6%b2%99%e7%94%b0%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u6c99\u7530\u5340<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.kidemy.hk\/blog\/%e5%90%84%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e8%b3%87%e8%a8%8a\/%e8%a5%bf%e8%b2%a2%e5%8d%80%e5%b9%bc%e7%a8%9a%e5%9c%92%e6%8e%92%e5%90%8d-2022\/\">\u897f\u8ca2\u5340<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg\" alt=\"\" class=\"wp-image-1342\" width=\"615\" height=\"320\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg 1024w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-300x156.jpg 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-768x399.jpg 768w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1536x798.jpg 1536w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-2048x1064.jpg 2048w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-693x360.jpg 693w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-390x203.jpg 390w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-396x206.jpg 396w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-288x150.jpg 288w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-268x139.jpg 268w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-253x131.jpg 253w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-103x53.jpg 103w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%9F%BA%E6%9C%AC%E8%B3%87%E6%96%99\"><\/span><img decoding=\"async\" width=\"30\" height=\"30\" class=\"wp-image-1321\" style=\"width: 30px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-school-120x120.png 120w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/> <strong>NORWEGIAN INTERNATIONAL SCHOOL<\/strong> \u57fa\u672c\u8cc7\u6599<span class=\"ez-toc-section-end\"><\/span><\/h2><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u76ee\u9304<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%9F%BA%E6%9C%AC%E8%B3%87%E6%96%99\" >NORWEGIAN INTERNATIONAL SCHOOL \u57fa\u672c\u8cc7\u6599<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%AD%B8%E6%A0%A1%E8%A8%AD%E6%96%BD\" >NORWEGIAN INTERNATIONAL SCHOOL \u5b78\u6821\u8a2d\u65bd<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#NORWEGIAN_INTERNATIONAL_SCHOOL_%E6%AF%8F%E7%8F%AD%E4%BA%BA%E6%95%B8\" >NORWEGIAN INTERNATIONAL SCHOOL \u6bcf\u73ed\u4eba\u6578<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%A5%BD%E5%94%94%E5%A5%BD\" >NORWEGIAN INTERNATIONAL SCHOOL \u597d\u5514\u597d?<\/a><\/li><\/ul><\/nav><\/div>\n\n\n\n\n<figure class=\"wp-block-table is-style-stripes table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><strong>\u5b78\u6821\u540d\u7a31:<\/strong><\/td><td>NORWEGIAN INTERNATIONAL SCHOOL-<br>NORWEGIAN INTERNATIONAL SCHOOL<\/td><td><strong>\u5168\u5e74\u5b78\u8cbb (\u534a\u65e5\u73ed):<\/strong><\/td><td>$71,260<\/td><\/tr><tr><td><strong>\u5730\u5740<\/strong>:<\/td><td>\u65b0\u754c\u5927\u57d4\u5ee3\u798f\u9053\u5927\u57d4\u5e73\u623f\u53ca\u9326\u5c71\u8def170\u865f<\/td><td><strong>\u5168\u5e74\u5b78\u8cbb (\u5168\u65e5\u73ed):<\/strong><\/td><td>$74,400<\/td><\/tr><tr><td><strong>\u5730\u5340:<\/strong><\/td><td>\u5927\u57d4\u5340<\/td><td><strong>\u5730\u5340\u6392\u540d<\/strong>:<\/td><td>&#8211;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table is-style-stripes table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><strong>\u6821\u9577:<\/strong><\/td><td>\u9673\u6167\u73ca\u5973\u58eb<\/td><\/tr><tr><td><strong>\u6821\u76e3:<\/strong><\/td><td>MRS APPEL TERRI CRYSTAL-GIBBS<\/td><\/tr><tr><td><strong>\u5275\u6821\u5e74\u4efd:<\/strong><\/td><td>1994<\/td><\/tr><tr><td><strong>\u5bb6\u9577\u6559\u5e2b\u6703:<\/strong><\/td><td>\u6709<\/td><\/tr><tr><td><strong>\u5b97\u6559:<\/strong><\/td><td>\u57fa\u7763\u6559<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table is-style-stripes table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><strong>\u6027\u5225:<\/strong><\/td><td>\u7537\u5973<\/td><\/tr><tr><td><strong>\u5e7c\u7a1a\u5712\u6559\u80b2\u8a08\u5283:<\/strong><\/td><td>\u6c92\u6709\u53c3\u52a0<\/td><\/tr><tr><td><strong>\u96fb\u8a71:<\/strong><\/td><td>26380269<\/td><\/tr><tr><td><strong>\u7db2\u5740:<\/strong><\/td><td><a href=\"http:\/\/www.nis.edu.hk\">http:\/\/www.nis.edu.hk<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:77px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%AD%B8%E6%A0%A1%E8%A8%AD%E6%96%BD\"><\/span><img decoding=\"async\" width=\"30\" height=\"30\" class=\"wp-image-1320\" style=\"width: 30px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-pole-120x120.png 120w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/> <strong>NORWEGIAN INTERNATIONAL SCHOOL<\/strong> \u5b78\u6821\u8a2d\u65bd<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table is-style-stripes table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><strong>\u8ab2\u5ba4\u6578\u76ee:<\/strong><\/td><td>4<\/td><\/tr><tr><td><strong>\u6236\u5916\u904a\u6232\u5834\u5730:<\/strong><\/td><td>\u6709<\/td><\/tr><tr><td><strong>\u5ba4\u5167\u904a\u6232\u5834\u5730:<\/strong><\/td><td>\u6c92\u6709<\/td><\/tr><tr><td><strong>\u97f3\u6a02\u5ba4:<\/strong><\/td><td>\u6709<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table is-style-stripes table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><strong>\u5176\u4ed6\u5834\u5730:<\/strong><\/td><td>\u79ae\u5802<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:77px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"NORWEGIAN_INTERNATIONAL_SCHOOL_%E6%AF%8F%E7%8F%AD%E4%BA%BA%E6%95%B8\"><\/span><img decoding=\"async\" width=\"30\" height=\"30\" class=\"wp-image-1323\" style=\"width: 30px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student1-120x120.png 120w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/><img decoding=\"async\" width=\"30\" height=\"30\" class=\"wp-image-1324\" style=\"width: 30px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-student2-120x120.png 120w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/><strong>NORWEGIAN INTERNATIONAL SCHOOL<\/strong> \u6bcf\u73ed\u4eba\u6578<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-regular table-odd-row\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>\u4e0a\u5348\u73ed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>\u4e0b\u5348\u73ed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>\u5168\u65e5\u73ed<\/strong><\/td><\/tr><tr><td><strong>\u5e7c\u5152\u73ed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><td class=\"has-text-align-center\" data-align=\"center\">24<\/td><td class=\"has-text-align-center\" data-align=\"center\">0<\/td><\/tr><tr><td><strong>\u4f4e\u73ed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">28<\/td><td class=\"has-text-align-center\" data-align=\"center\">18<\/td><td class=\"has-text-align-center\" data-align=\"center\">0<br><\/td><\/tr><tr><td><strong>\u9ad8\u73ed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">0<\/td><td class=\"has-text-align-center\" data-align=\"center\">42<\/td><td class=\"has-text-align-center\" data-align=\"center\">0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:77px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"NORWEGIAN_INTERNATIONAL_SCHOOL_%E5%A5%BD%E5%94%94%E5%A5%BD\"><\/span><img decoding=\"async\" width=\"30\" height=\"30\" class=\"wp-image-1319\" style=\"width: 30px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-lightblub-120x120.png 120w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/> <strong>NORWEGIAN INTERNATIONAL SCHOOL<\/strong> \u597d\u5514\u597d?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u8ab2\u7a0b\u898f\u5283<\/strong>\uff1a<\/td><\/tr><tr><td>\u570b\u969b\u65e9\u5e74\u6559\u80b2\u8ab2\u7a0b\uff08IEYC\uff09\uff1b\u82f1\u8a9e\uff1b\u62fc\u97f3\uff1b\u6578\u5b78\uff1b\u666e\u901a\u8a71\uff1b\u97f3\u6a02\uff1b\u85dd\u8853\uff1b\u9ad4\u80fd\u6559\u80b2\uff1b\u57fa\u7763\u6559\u5b78\u7fd2\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u6559\u5b78\u6a21\u5f0f\u53ca\u6d3b\u52d5<\/strong>\uff1a<\/td><\/tr><tr><td>\u5c0f\u73ed\u6559\u5b78\uff1b\u500b\u5225\u8f14\u5c0e\uff1b\u5404\u7a2e\u5404\u6a23\u7684\u6d3b\u52d5\u5305\u62ec\u5230\u7345\u5b50\u6703\u81ea\u7136\u6559\u80b2\u4e2d\u5fc3\u3001\u7576\u5730\u5716\u66f8\u9928\u9032\u884c\u5be6\u5730\u53c3\u89c0\uff0c\u4ee5\u53ca\u904b\u52d5\u65e5\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u5b78\u6821\u4f7f\u547d\u53ca\u62b1\u8ca0<\/strong>\uff1a<\/td><\/tr><tr><td>\u5728\u6eab\u6696\u5982\u5bb6\u7684\u74b0\u5883\u4e2d\u57f9\u990a\u81ea\u4fe1\u7684\u5b78\u7fd2\u8005\u53ca\u8ca0\u8cac\u4efb\u7684\u5168\u7403\u516c\u6c11\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u5c0d\u5b78\u751f\u652f\u63f4<\/strong>\uff1a<\/td><\/tr><tr><td>\u6839\u64da\u500b\u5225\u60c5\u6cc1\uff0c\u7531\u8001\u5e2b\u5b89\u6392\u5c0d\u6709\u7279\u5b9a\u5b78\u7fd2\u9700\u6c42\u7684\u5b78\u751f\u63d0\u4f9b\u652f\u63f4\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u5152\u7ae5\u5b78\u7fd2\u7d93\u9a57\u8a55\u4f30<\/strong>\uff1a<\/td><\/tr><tr><td>\u570b\u969b\u5c0f\u5b78\u8ab2\u7a0b(IPC)\u53ca\u8ab2\u7a0b\u8a55\u4f30\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table table-odd-row is-style-regular\"><table><tbody><tr><\/tr><tr><\/tr><tr><td><img decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-1322\" style=\"width: 20px;\" src=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png\" alt=\"\" srcset=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star.png 500w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-300x300.png 300w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-150x150.png 150w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-40x40.png 40w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-220x220.png 220w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-360x360.png 360w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-260x260.png 260w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-215x215.png 215w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-325x325.png 325w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-190x190.png 190w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-148x148.png 148w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-189x189.png 189w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-68x68.png 68w, https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/tmp-kgen-details-star-120x120.png 120w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/> <strong>\u5176\u4ed6\u5bb6\u9577\u6d3b\u52d5<\/strong>\uff1a<\/td><\/tr><tr><td>\u7c4c\u8cc7\u3001\u665a\u9910\u3001\u5de5\u4f5c\u574a\u3001\u901a\u8a0a\u3001\u6236\u5916\u5be6\u5730\u8003\u5bdf\u3002<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:77px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u4e2d\u897f\u5340 \u7063\u4ed4\u5340 \u6771\u5340 \u5357\u5340 \u6cb9\u5c16\u65fa\u5340 \u6df1\u6c34\u57d7\u5340 \u4e5d\u9f8d\u57ce\u5340 \u9ec3\u5927\u4ed9\u5340 \u89c0\u5858\u5340 \u8475\u9752\u5340 \u8343\u7063\u5340 \u5c6f\u9580\u5340 \u5143\u6717\u5340 \u96e2\u5cf6\u5340 \u5317\u5340 \u5927\u57d4\u5340 \u6c99\u7530\u5340 \u897f\u8ca2\u5340 NORWEGIAN INTERNATIONAL SCHOOL \u57fa\u672c\u8cc7\u6599 \u5b78\u6821\u540d\u7a31: NORWEGIAN INTERNATIONAL SCHOOL-NORWEGIAN INTERNATIONAL SCHOOL \u5168\u5e74\u5b78\u8cbb (\u534a\u65e5\u73ed): $71,260 \u5730\u5740: \u65b0\u754c\u5927\u57d4\u5ee3\u798f\u9053\u5927\u57d4\u5e73\u623f\u53ca\u9326\u5c71\u8def170\u865f \u5168\u5e74\u5b78\u8cbb (\u5168\u65e5\u73ed): $74,400 \u5730\u5340: \u5927\u57d4\u5340 \u5730\u5340\u6392\u540d: &#8211; \u6821\u9577: \u9673\u6167\u73ca\u5973\u58eb \u6821\u76e3: MRS APPEL TERRI CRYSTAL-GIBBS \u5275\u6821\u5e74\u4efd: 1994 \u5bb6\u9577\u6559\u5e2b\u6703: \u6709 \u5b97\u6559: \u57fa\u7763\u6559 \u6027\u5225: \u7537\u5973 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2001","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy\" \/>\n<meta property=\"og:description\" content=\"\u4e2d\u897f\u5340 \u7063\u4ed4\u5340 \u6771\u5340 \u5357\u5340 \u6cb9\u5c16\u65fa\u5340 \u6df1\u6c34\u57d7\u5340 \u4e5d\u9f8d\u57ce\u5340 \u9ec3\u5927\u4ed9\u5340 \u89c0\u5858\u5340 \u8475\u9752\u5340 \u8343\u7063\u5340 \u5c6f\u9580\u5340 \u5143\u6717\u5340 \u96e2\u5cf6\u5340 \u5317\u5340 \u5927\u57d4\u5340 \u6c99\u7530\u5340 \u897f\u8ca2\u5340 NORWEGIAN INTERNATIONAL SCHOOL \u57fa\u672c\u8cc7\u6599 \u5b78\u6821\u540d\u7a31: NORWEGIAN INTERNATIONAL SCHOOL-NORWEGIAN INTERNATIONAL SCHOOL \u5168\u5e74\u5b78\u8cbb (\u534a\u65e5\u73ed): $71,260 \u5730\u5740: \u65b0\u754c\u5927\u57d4\u5ee3\u798f\u9053\u5927\u57d4\u5e73\u623f\u53ca\u9326\u5c71\u8def170\u865f \u5168\u5e74\u5b78\u8cbb (\u5168\u65e5\u73ed): $74,400 \u5730\u5340: \u5927\u57d4\u5340 \u5730\u5340\u6392\u540d: &#8211; \u6821\u9577: \u9673\u6167\u73ca\u5973\u58eb \u6821\u76e3: MRS APPEL TERRI CRYSTAL-GIBBS \u5275\u6821\u5e74\u4efd: 1994 \u5bb6\u9577\u6559\u5e2b\u6703: \u6709 \u5b97\u6559: \u57fa\u7763\u6559 \u6027\u5225: \u7537\u5973 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/\" \/>\n<meta property=\"og:site_name\" content=\"\u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100093218085328\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-16T14:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/\",\"url\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/\",\"name\":\"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy\",\"isPartOf\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg\",\"datePublished\":\"2022-09-05T14:34:12+00:00\",\"dateModified\":\"2023-07-16T14:55:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage\",\"url\":\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg\",\"contentUrl\":\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.kidemy.hk\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? &#8211; 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#website\",\"url\":\"https:\/\/www.kidemy.hk\/blog\/\",\"name\":\"\u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy\",\"description\":\"\u9999\u6e2f\u5bb6\u9577\u5fc5\u7747\u8208\u8da3\u73ed\u8207\u5347\u5b78\u6307\u5357\",\"publisher\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kidemy.hk\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#organization\",\"name\":\"Kidemy\",\"url\":\"https:\/\/www.kidemy.hk\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/02\/logo-K-03june.png\",\"contentUrl\":\"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/02\/logo-K-03june.png\",\"width\":400,\"height\":400,\"caption\":\"Kidemy\"},\"image\":{\"@id\":\"https:\/\/www.kidemy.hk\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100093218085328\",\"https:\/\/www.youtube.com\/channel\/UCDsKf1ABrqYYAu_NruKWRzw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/","og_locale":"en_US","og_type":"article","og_title":"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy","og_description":"\u4e2d\u897f\u5340 \u7063\u4ed4\u5340 \u6771\u5340 \u5357\u5340 \u6cb9\u5c16\u65fa\u5340 \u6df1\u6c34\u57d7\u5340 \u4e5d\u9f8d\u57ce\u5340 \u9ec3\u5927\u4ed9\u5340 \u89c0\u5858\u5340 \u8475\u9752\u5340 \u8343\u7063\u5340 \u5c6f\u9580\u5340 \u5143\u6717\u5340 \u96e2\u5cf6\u5340 \u5317\u5340 \u5927\u57d4\u5340 \u6c99\u7530\u5340 \u897f\u8ca2\u5340 NORWEGIAN INTERNATIONAL SCHOOL \u57fa\u672c\u8cc7\u6599 \u5b78\u6821\u540d\u7a31: NORWEGIAN INTERNATIONAL SCHOOL-NORWEGIAN INTERNATIONAL SCHOOL \u5168\u5e74\u5b78\u8cbb (\u534a\u65e5\u73ed): $71,260 \u5730\u5740: \u65b0\u754c\u5927\u57d4\u5ee3\u798f\u9053\u5927\u57d4\u5e73\u623f\u53ca\u9326\u5c71\u8def170\u865f \u5168\u5e74\u5b78\u8cbb (\u5168\u65e5\u73ed): $74,400 \u5730\u5340: \u5927\u57d4\u5340 \u5730\u5340\u6392\u540d: &#8211; \u6821\u9577: \u9673\u6167\u73ca\u5973\u58eb \u6821\u76e3: MRS APPEL TERRI CRYSTAL-GIBBS \u5275\u6821\u5e74\u4efd: 1994 \u5bb6\u9577\u6559\u5e2b\u6703: \u6709 \u5b97\u6559: \u57fa\u7763\u6559 \u6027\u5225: \u7537\u5973 [&hellip;]","og_url":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/","og_site_name":"\u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100093218085328","article_modified_time":"2023-07-16T14:55:46+00:00","og_image":[{"url":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/","url":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/","name":"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? - 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a - \u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy","isPartOf":{"@id":"https:\/\/www.kidemy.hk\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage"},"image":{"@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg","datePublished":"2022-09-05T14:34:12+00:00","dateModified":"2023-07-16T14:55:46+00:00","breadcrumb":{"@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#primaryimage","url":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg","contentUrl":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/08\/school-ranking-stock-3-1024x532.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kidemy.hk\/blog\/norwegian-international-school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.kidemy.hk\/blog\/"},{"@type":"ListItem","position":2,"name":"NORWEGIAN INTERNATIONAL SCHOOL\u597d\u5514\u597d? &#8211; 2024\/25 \u6700\u65b0\u5b78\u6821\u53ca\u5165\u5b78\u8cc7\u8a0a"}]},{"@type":"WebSite","@id":"https:\/\/www.kidemy.hk\/blog\/#website","url":"https:\/\/www.kidemy.hk\/blog\/","name":"\u9999\u6e2f\u5bb6\u9577\u6559\u80b2\u8cc7\u8a0a\u5e73\u53f0\uff5c\u8208\u8da3\u73ed\u30fb\u5347\u5b78\u30fb\u9762\u8a66\u653b\u7565\uff5cKidemy","description":"\u9999\u6e2f\u5bb6\u9577\u5fc5\u7747\u8208\u8da3\u73ed\u8207\u5347\u5b78\u6307\u5357","publisher":{"@id":"https:\/\/www.kidemy.hk\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kidemy.hk\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.kidemy.hk\/blog\/#organization","name":"Kidemy","url":"https:\/\/www.kidemy.hk\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kidemy.hk\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/02\/logo-K-03june.png","contentUrl":"https:\/\/www.kidemy.hk\/blog\/wp-content\/uploads\/2022\/02\/logo-K-03june.png","width":400,"height":400,"caption":"Kidemy"},"image":{"@id":"https:\/\/www.kidemy.hk\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100093218085328","https:\/\/www.youtube.com\/channel\/UCDsKf1ABrqYYAu_NruKWRzw"]}]}},"_links":{"self":[{"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/pages\/2001"}],"collection":[{"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/comments?post=2001"}],"version-history":[{"count":1,"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/pages\/2001\/revisions"}],"predecessor-version":[{"id":5163,"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/pages\/2001\/revisions\/5163"}],"wp:attachment":[{"href":"https:\/\/www.kidemy.hk\/blog\/wp-json\/wp\/v2\/media?parent=2001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}